{"id":5197,"count":1,"description":"","link":"https:\/\/yllalive.com\/games\/tag\/arcade-archives-2-neo-geo\/","name":"Arcade Archives 2 Neo Geo","slug":"arcade-archives-2-neo-geo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/yllalive.com\/games\/wp-json\/wp\/v2\/tags\/5197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yllalive.com\/games\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/yllalive.com\/games\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/yllalive.com\/games\/wp-json\/wp\/v2\/posts?tags=5197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}